{"id":52,"date":"2024-09-20T13:35:45","date_gmt":"2024-09-20T11:35:45","guid":{"rendered":"https:\/\/technikum.certyfikaty.edu.pl\/?page_id=52"},"modified":"2026-05-22T08:39:28","modified_gmt":"2026-05-22T06:39:28","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;7px||10px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;49px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||24px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<hr>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;50px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Szko\u0142a Techniczna im. Dywizjonu 303 Bydgoskiego Zak\u0142adu Doskonalenia Zawodowego w Chojnicach<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||24px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<hr>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;800px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_radii=&#8221;on|35px|35px|35px|35px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-content\/uploads\/2025\/05\/anna-henszke.png&#8221; title_text=&#8221;Anna Henszke&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e6e7e8&#8243; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|35px|35px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_2_text_color=&#8221;#000000&#8243; background_color=&#8221;#FFFFFF&#8221; position_origin_a=&#8221;bottom_center&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;21px||21px||true|false&#8221; text_text_shadow_style=&#8221;preset5&#8243; text_text_shadow_color=&#8221;#FFFFFF&#8221; header_2_text_shadow_style=&#8221;preset5&#8243; header_2_text_shadow_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;off|||35px|35px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Henszke Anna<\/h2>\n<p style=\"text-align: center;\">Dyrektorka<\/p>\n<p style=\"text-align: center;\"><a href=\"mailto:anna.henszke@bzdz.pl\">anna.henszke@bzdz.pl<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_radii=&#8221;on|35px|35px|35px|35px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-content\/uploads\/2025\/10\/walewska-lidia-1-1.png&#8221; title_text=&#8221;Walewska Lidia (1)&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e6e7e8&#8243; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|35px|35px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_2_text_color=&#8221;#000000&#8243; background_color=&#8221;#FFFFFF&#8221; position_origin_a=&#8221;bottom_center&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;21px||21px||true|false&#8221; text_text_shadow_style=&#8221;preset5&#8243; text_text_shadow_color=&#8221;#FFFFFF&#8221; header_2_text_shadow_style=&#8221;preset5&#8243; header_2_text_shadow_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;off|||35px|35px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Walewska Lidia<\/h2>\n<p style=\"text-align: center;\">Wicedyrektorka<\/p>\n<p style=\"text-align: center;\"><a href=\"mailto:lidia.walewska@bzdz.pl\">lidia.walewska@bzdz.pl<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_radii=&#8221;on|35px|35px|35px|35px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-content\/uploads\/2025\/10\/redlarski-maciej-1.png&#8221; title_text=&#8221;Redlarski Maciej&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e6e7e8&#8243; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|35px|35px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_2_text_color=&#8221;#000000&#8243; background_color=&#8221;#FFFFFF&#8221; position_origin_a=&#8221;bottom_center&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;21px||21px||true|false&#8221; text_text_shadow_style=&#8221;preset5&#8243; text_text_shadow_color=&#8221;#FFFFFF&#8221; header_2_text_shadow_style=&#8221;preset5&#8243; header_2_text_shadow_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;off|||35px|35px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Redlarski Maciej<\/h2>\n<p style=\"text-align: center;\">Wicedyrektor<\/p>\n<p style=\"text-align: center;\"><a href=\"mailto:lidia.walewska@bzdz.pl\">maciej.redlarski@bzdz.pl<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;800px&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_radii=&#8221;on|35px|35px|35px|35px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-content\/uploads\/2025\/10\/kniter-krystian-1.png&#8221; title_text=&#8221;Justyna Chabowska &#8211; kontakt&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e6e7e8&#8243; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|35px|35px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_2_text_color=&#8221;#000000&#8243; background_color=&#8221;#FFFFFF&#8221; position_origin_a=&#8221;bottom_center&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;21px||21px||true|false&#8221; text_text_shadow_style=&#8221;preset5&#8243; text_text_shadow_color=&#8221;#FFFFFF&#8221; header_2_text_shadow_style=&#8221;preset5&#8243; header_2_text_shadow_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;off|||35px|35px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Marzena Stawicka<\/h2>\n<p style=\"text-align: center;\">Specjalistka ds. administracyjno-biurowych<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_radii=&#8221;on|35px|35px|35px|35px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-content\/uploads\/2024\/09\/anna-halasowska-kontakt.png&#8221; title_text=&#8221;Anna Ha\u0142asowska &#8211; kontakt&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e6e7e8&#8243; custom_margin=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;off|35px|35px||&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_2_text_color=&#8221;#000000&#8243; background_color=&#8221;#FFFFFF&#8221; position_origin_a=&#8221;bottom_center&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;21px||21px||true|false&#8221; text_text_shadow_style=&#8221;preset5&#8243; text_text_shadow_color=&#8221;#FFFFFF&#8221; header_2_text_shadow_style=&#8221;preset5&#8243; header_2_text_shadow_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;off|||35px|35px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Anna Ha\u0142asowska<\/h2>\n<p style=\"text-align: center;\">Kierowniczka ds. administracyjno-technicznych<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_radii=&#8221;on|35px|35px|35px|35px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-content\/uploads\/2025\/10\/kniter-krystian-1.png&#8221; title_text=&#8221;Justyna Chabowska &#8211; kontakt&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e6e7e8&#8243; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|35px|35px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_2_text_color=&#8221;#000000&#8243; background_color=&#8221;#FFFFFF&#8221; position_origin_a=&#8221;bottom_center&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;21px||21px||true|false&#8221; text_text_shadow_style=&#8221;preset5&#8243; text_text_shadow_color=&#8221;#FFFFFF&#8221; header_2_text_shadow_style=&#8221;preset5&#8243; header_2_text_shadow_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;off|||35px|35px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Anna Karpacz<\/h2>\n<p style=\"text-align: center;\">Pomoc administracyjna<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||26px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||10px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<hr>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||20px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||24px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<hr>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#ee6813&#8243; header_2_font_size=&#8221;2.6rem&#8221; max_width=&#8221;600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;50px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Kontakt<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;600px&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;8px||7px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf3cd;||fa||900&#8243; icon_color=&#8221;#FFFFFF&#8221; image_icon_width=&#8221;3rem&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; body_text_color=&#8221;#ee6813&#8243; link_option_url=&#8221;tel:882616197&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>882 616 197<\/strong><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf0e0;||fa||400&#8243; icon_color=&#8221;#FFFFFF&#8221; image_icon_width=&#8221;3rem&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; body_text_color=&#8221;#ee6813&#8243; link_option_url=&#8221;mailto:chojnice@bzdz.pl&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>chojnice@bzdz.pl<\/strong><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; title_text_align=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;90px||2rem||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_post_title][et_pb_fullwidth_image src=&#8221;https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-content\/uploads\/2025\/10\/foto.jpg&#8221; title_text=&#8221;kontakt-okladka&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;6px||5px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-4px|auto||auto||&#8221; custom_padding=&#8221;19px||7px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||15px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\">Sekretariat czynny od poniedzia\u0142ku do pi\u0105tku w godzinach 8:00 &#8211; 16:00<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||7px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||59px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#ee6813&#8243; header_2_font_size=&#8221;2.6rem&#8221; max_width=&#8221;600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;50px||23px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Adres<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||28px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\">ul. Ko\u015bcierska 10, 89-600 Chojnice<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_code _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d4010.786713940367!2d17.56888841342543!3d53.697218372278016!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x47024642cec1f493%3A0xc08e2f0ca1844836!2sKo%C5%9Bcierska%2010%2C%2089-620%20Chojnice!5e1!3m2!1sen!2spl!4v1727344925742!5m2!1sen!2spl\" width=\"100%\" height=\"550\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_fullwidth_code][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;45px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||3px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||59px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#ee6813&#8243; max_width=&#8221;600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;50px||23px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Nasze media spo\u0142eczno\u015bciowe<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;300px&#8221; custom_padding=&#8221;14px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_icon font_icon=&#8221;&#xe09a;||divi||400&#8243; icon_color=&#8221;#FFFFFF&#8221; icon_width=&#8221;3rem&#8221; url=&#8221;https:\/\/www.instagram.com\/bzdz_chojnice\/&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_icon font_icon=&#8221;&#xf09a;||fa||400&#8243; icon_color=&#8221;#FFFFFF&#8221; icon_width=&#8221;3rem&#8221; url=&#8221;https:\/\/www.facebook.com\/techmundurowechojnice\/&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_icon font_icon=&#8221;&#xe07b;||fa||400&#8243; icon_color=&#8221;#FFFFFF&#8221; icon_width=&#8221;3rem&#8221; url=&#8221;https:\/\/www.tiktok.com\/@bzdz.chojnice&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;30px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||55px||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; header_2_font_size=&#8221;2.5rem&#8221; custom_margin=&#8221;||2rem||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Pytania? Skontaktuj si\u0119 z nami!<\/h2>\n<p>[\/et_pb_text][et_pb_contact_form email=&#8221;chojnice@bzdz.pl&#8221; submit_button_text=&#8221;Wy\u015blij wiadomo\u015b\u0107&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;b7e29585-a43e-4cad-912d-07a18036e572&#8243; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Imi\u0119 i nazwisko&#8221; _builder_version=&#8221;4.27.0&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;E-mail&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.27.0&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Message&#8221; field_title=&#8221;Twoja wiadomo\u015b\u0107&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.27.0&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Szko\u0142a Techniczna im. Dywizjonu 303 Bydgoskiego Zak\u0142adu Doskonalenia Zawodowego w ChojnicachHenszke Anna Dyrektorka anna.henszke@bzdz.plWalewska Lidia Wicedyrektorka lidia.walewska@bzdz.plRedlarski Maciej Wicedyrektor maciej.redlarski@bzdz.plMarzena Stawicka Specjalistka ds. administracyjno-biurowychAnna Ha\u0142asowska Kierowniczka ds. administracyjno-technicznychAnna Karpacz Pomoc administracyjnaKontakt882 616 197chojnice@bzdz.plSekretariat czynny od poniedzia\u0142ku do pi\u0105tku w godzinach 8:00 &#8211; 16:00Adresul. Ko\u015bcierska 10, 89-600 ChojniceNasze media spo\u0142eczno\u015bciowePytania? Skontaktuj si\u0119 z nami!<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-52","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kontakt - Technikum Chojnice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kontakt - Technikum Chojnice\" \/>\n<meta property=\"og:description\" content=\"Szko\u0142a Techniczna im. Dywizjonu 303 Bydgoskiego Zak\u0142adu Doskonalenia Zawodowego w ChojnicachHenszke Anna Dyrektorka anna.henszke@bzdz.plWalewska Lidia Wicedyrektorka lidia.walewska@bzdz.plRedlarski Maciej Wicedyrektor maciej.redlarski@bzdz.plMarzena Stawicka Specjalistka ds. administracyjno-biurowychAnna Ha\u0142asowska Kierowniczka ds. administracyjno-technicznychAnna Karpacz Pomoc administracyjnaKontakt882 616 197chojnice@bzdz.plSekretariat czynny od poniedzia\u0142ku do pi\u0105tku w godzinach 8:00 - 16:00Adresul. Ko\u015bcierska 10, 89-600 ChojniceNasze media spo\u0142eczno\u015bciowePytania? Skontaktuj si\u0119 z nami!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/\" \/>\n<meta property=\"og:site_name\" content=\"Technikum Chojnice\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T06:39:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/kontakt\\\/\",\"url\":\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/kontakt\\\/\",\"name\":\"Kontakt - Technikum Chojnice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/#website\"},\"datePublished\":\"2024-09-20T11:35:45+00:00\",\"dateModified\":\"2026-05-22T06:39:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/kontakt\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/kontakt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/kontakt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kontakt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/#website\",\"url\":\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/\",\"name\":\"Technikum Chojnice\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bzdz.pl\\\/technikum-mundurowe-chojnice\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kontakt - Technikum Chojnice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/","og_locale":"pl_PL","og_type":"article","og_title":"Kontakt - Technikum Chojnice","og_description":"Szko\u0142a Techniczna im. Dywizjonu 303 Bydgoskiego Zak\u0142adu Doskonalenia Zawodowego w ChojnicachHenszke Anna Dyrektorka anna.henszke@bzdz.plWalewska Lidia Wicedyrektorka lidia.walewska@bzdz.plRedlarski Maciej Wicedyrektor maciej.redlarski@bzdz.plMarzena Stawicka Specjalistka ds. administracyjno-biurowychAnna Ha\u0142asowska Kierowniczka ds. administracyjno-technicznychAnna Karpacz Pomoc administracyjnaKontakt882 616 197chojnice@bzdz.plSekretariat czynny od poniedzia\u0142ku do pi\u0105tku w godzinach 8:00 - 16:00Adresul. Ko\u015bcierska 10, 89-600 ChojniceNasze media spo\u0142eczno\u015bciowePytania? Skontaktuj si\u0119 z nami!","og_url":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/","og_site_name":"Technikum Chojnice","article_modified_time":"2026-05-22T06:39:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/","url":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/","name":"Kontakt - Technikum Chojnice","isPartOf":{"@id":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/#website"},"datePublished":"2024-09-20T11:35:45+00:00","dateModified":"2026-05-22T06:39:28+00:00","breadcrumb":{"@id":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/kontakt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/"},{"@type":"ListItem","position":2,"name":"Kontakt"}]},{"@type":"WebSite","@id":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/#website","url":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/","name":"Technikum Chojnice","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-json\/wp\/v2\/pages\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":20,"href":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-json\/wp\/v2\/pages\/52\/revisions"}],"predecessor-version":[{"id":22333,"href":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-json\/wp\/v2\/pages\/52\/revisions\/22333"}],"wp:attachment":[{"href":"https:\/\/www.bzdz.pl\/technikum-mundurowe-chojnice\/wp-json\/wp\/v2\/media?parent=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}